{"id":156,"date":"2019-11-05T02:30:46","date_gmt":"2019-11-05T02:30:46","guid":{"rendered":"https:\/\/demo.casethemes.net\/consultio-finance2\/?p=156"},"modified":"2022-09-03T21:11:40","modified_gmt":"2022-09-03T21:11:40","slug":"reasons-to-explan-fast-business-builder","status":"publish","type":"post","link":"https:\/\/www.todoreiki.org\/index.php\/2019\/11\/05\/reasons-to-explan-fast-business-builder\/","title":{"rendered":"El Reiki como forma terap\u00e9utica en el cuidado de la salud"},"content":{"rendered":"<div class=\"entry-content clear\">\n<p>El Reiki es una pr\u00e1ctica espiritual con las dimensiones basadas en la materia y esp\u00edritu, <strong>caracterizado por la imposici\u00f3n de manos con el fin de restablecer el equilibrio del cuerpo.<\/strong> Este es uno de los m\u00e9todos curativos m\u00e1s antiguos de que la humanidad tiene conocimiento. Se origin\u00f3 en el T\u00edbet hace dieciocho siglos y fue redescubierto en el siglo XIX por un monje japon\u00e9s llamado Mikao Usui. La tradici\u00f3n del reiki se remonta a escritos de 2.500 a\u00f1os en s\u00e1nscrito, la lengua antigua de la India.<\/p>\n<p>El Reiki es una terapia curativa natural segura, hol\u00edstica, pues trata al ser humano como un todo, f\u00e1cil de usar y puede tratar muchas enfermedades agudas y cr\u00f3nicas, tales como: <strong>sinusitis, rinitis, asma, cistitis, fatiga cr\u00f3nica, artritis, ci\u00e1tica, insomnio, depresi\u00f3n, promover el bienestar espiritual, mental y emocional<\/strong>. Es conveniente para todas las personas, sin restricciones. Es un excelente t\u00f3nico y si usted est\u00e1 en buena condici\u00f3n f\u00edsica, el reiki le ayudar\u00e1 a seguir as\u00ed.<\/p>\n<p>Esta t\u00e9cnica japonesa llamada reiki, se utiliza para reducir el estr\u00e9s y sirve para la relajaci\u00f3n que tambi\u00e9n promueve la curaci\u00f3n. Se lleva a cabo por un profesional capacitado mediante la imposici\u00f3n de las manos en el individuo. Se basa en la idea de que la energ\u00eda fluye a trav\u00e9s de nosotros y puede utilizarse para estimular el proceso de curaci\u00f3n. El uso de reiki como terapia complementaria est\u00e1 creciendo r\u00e1pidamente, siendo utilizado en muchos hospitales en los Estados Unidos y Europa para ayudar a aliviar el dolor y aumentar las tasas de recuperaci\u00f3n.<\/p>\n<p>Aunque todos tenemos la habilidad innata para imponer las manos, en el sistema reiki el desbloqueo de los chakras (\u00abrueda de luz\u00bb. Son puntos de energ\u00eda de diferentes vibraciones, representando diferentes aspectos del cuerpo, del alma y del esp\u00edritu. Simbolizan la ley de la naturaleza, estando en constante movimiento. Se localizan a lo largo de la columna vertebral del cuerpo humano; su funci\u00f3n es la de recibir y transmitir energ\u00eda a las \u00e1reas afectadas del cuerpo f\u00edsico, trayendo el equilibrio) ocurre con el ritual de iniciaci\u00f3n, momento en que los canales de energ\u00eda se abren, permitiendo empezar a sintonizar con la Energ\u00eda Universal y as\u00ed convertirse en un agente de cura y puede actuar como terapeuta reiki.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Reiki es una pr\u00e1ctica espiritual con las dimensiones basadas en la materia y esp\u00edritu, caracterizado por la imposici\u00f3n de manos con el fin de restablecer el equilibrio del cuerpo. Este es uno de los m\u00e9todos curativos m\u00e1s antiguos de que la humanidad tiene conocimiento. Se origin\u00f3 en el T\u00edbet hace dieciocho siglos y fue [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5441,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":"","_joinchat":[]},"categories":[1],"tags":[4,6,7],"_links":{"self":[{"href":"https:\/\/www.todoreiki.org\/index.php\/wp-json\/wp\/v2\/posts\/156"}],"collection":[{"href":"https:\/\/www.todoreiki.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.todoreiki.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.todoreiki.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.todoreiki.org\/index.php\/wp-json\/wp\/v2\/comments?post=156"}],"version-history":[{"count":2,"href":"https:\/\/www.todoreiki.org\/index.php\/wp-json\/wp\/v2\/posts\/156\/revisions"}],"predecessor-version":[{"id":5442,"href":"https:\/\/www.todoreiki.org\/index.php\/wp-json\/wp\/v2\/posts\/156\/revisions\/5442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.todoreiki.org\/index.php\/wp-json\/wp\/v2\/media\/5441"}],"wp:attachment":[{"href":"https:\/\/www.todoreiki.org\/index.php\/wp-json\/wp\/v2\/media?parent=156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.todoreiki.org\/index.php\/wp-json\/wp\/v2\/categories?post=156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.todoreiki.org\/index.php\/wp-json\/wp\/v2\/tags?post=156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}